{"id":1022,"date":"2025-07-16T17:21:11","date_gmt":"2025-07-16T15:21:11","guid":{"rendered":"https:\/\/www.avvinamento.it\/?p=1022"},"modified":"2025-07-21T15:57:11","modified_gmt":"2025-07-21T13:57:11","slug":"il-ristorante-dei-cacciatori-avvinamento","status":"publish","type":"post","link":"https:\/\/www.avvinamento.it\/index.php\/2025\/07\/16\/il-ristorante-dei-cacciatori-avvinamento\/","title":{"rendered":"AVVINAMENTO &amp; RISTORANTE DEI CACCIATORI"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1022\" class=\"elementor elementor-1022\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ac5a1f elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"3ac5a1f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-157a03b elementor-widget elementor-widget-text-editor\" data-id=\"157a03b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ed eccoci giunti alla terza serata. Le nostre papille gustative saranno stuzzicate e coccolate dai piatti che ci verranno proposti dal <strong>Ristorante dei Cacciatori<\/strong> nel centro di Givoletto.<\/p><p>Ogni serata \u00e8 a s\u00e8 stante, ma chi parteciper\u00e0 a tutte e 4 ricever\u00e0 4 omaggi super &#8220;vinosi&#8221;.<\/p><p>L\u2019evento avr\u00e0 un costo di <em><span style=\"color: #950000;\"><strong>\u20ac 40,00<\/strong><\/span><\/em> e si terr\u00e0 presso<em><span style=\"color: #950000;\"><strong> Il Ristorante dei Cacciatori in Via Rivasacco 2 a Givoletto, il 18 Luglio alle ore 20:30<\/strong><\/span><\/em><em><span style=\"color: #950000;\"><strong>.\u00a0<\/strong><\/span><\/em><\/p><p><strong><span style=\"text-decoration: underline; color: #950000;\"><span style=\"color: #950000;\">Serata a numero chiuso, prenotazione obbligatoria.<\/span><\/span><\/strong><\/p><p><em><b><span style=\"color: #950000;\">Ti aspettiamo!<\/span><\/b><\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8a4e982 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"8a4e982\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d3df32 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1d3df32\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;,&quot;_animation_delay&quot;:1000}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">IL RISTORANTE DEI CACCIATORI E AVVINAMENTO<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c23d2d3 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c23d2d3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;,&quot;_animation_delay&quot;:1300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">3+1...\u00e8 meglio di 1<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7398c68 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"7398c68\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-da318cf e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"da318cf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;triangle&quot;}\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,98.9L0,6.1V0h1000v6.1L500,98.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b3434d8 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"b3434d8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-658b281 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"658b281\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b6100c6 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"b6100c6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37d6bec elementor-widget elementor-widget-heading\" data-id=\"37d6bec\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Via Rivasacco 2, Givoletto<br>18 Luglio h. 20.30<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8dfb481 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"8dfb481\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-243b258 elementor-widget elementor-widget-text-editor\" data-id=\"243b258\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ed eccoci giunti alla terza serata. Le nostre papille gustative saranno stuzzicate e coccolate dai piatti che ci verranno proposti dal <strong>Ristorante dei Cacciatori<\/strong> nel centro di Givoletto.<\/p><p>Ogni serata \u00e8 a s\u00e8 stante, ma chi parteciper\u00e0 a tutte e 4 ricever\u00e0 4 omaggi super &#8220;vinosi&#8221;.<\/p><p>L\u2019evento avr\u00e0 un costo di <em><span style=\"color: #950000;\"><strong>\u20ac 40,00<\/strong><\/span><\/em> e si terr\u00e0 presso<em><span style=\"color: #950000;\"><strong> Il Ristorante dei Cacciatori in Via Rivasacco 2 a Givoletto, il 18 Luglio alle ore 20:30<\/strong><\/span><\/em><em><span style=\"color: #950000;\"><strong>.\u00a0<\/strong><\/span><\/em><\/p><p><strong><span style=\"text-decoration: underline; color: #950000;\"><span style=\"color: #950000;\">Serata a numero chiuso, prenotazione obbligatoria.<\/span><\/span><\/strong><\/p><p><em><b><span style=\"color: #950000;\">Ti aspettiamo!<\/span><\/b><\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-867683d elementor-widget elementor-widget-spacer\" data-id=\"867683d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9dd994e e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"9dd994e\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6b5af95 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"6b5af95\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a22f338 elementor-widget elementor-widget-image\" data-id=\"a22f338\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/LOCANDINA-1-819x1024.jpg\" class=\"attachment-large size-large wp-image-1023\" alt=\"\" srcset=\"https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/LOCANDINA-1-819x1024.jpg 819w, https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/LOCANDINA-1-240x300.jpg 240w, https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/LOCANDINA-1-768x960.jpg 768w, https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/LOCANDINA-1-1000x1250.jpg 1000w, https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/LOCANDINA-1-230x288.jpg 230w, https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/LOCANDINA-1-350x438.jpg 350w, https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/LOCANDINA-1-480x600.jpg 480w, https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/LOCANDINA-1.jpg 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4602316 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"4602316\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae4aed7 elementor-widget elementor-widget-image\" data-id=\"ae4aed7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/MENU-819x1024.jpg\" class=\"attachment-large size-large wp-image-1025\" alt=\"\" srcset=\"https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/MENU-819x1024.jpg 819w, https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/MENU-240x300.jpg 240w, https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/MENU-768x960.jpg 768w, https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/MENU-1000x1250.jpg 1000w, https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/MENU-230x288.jpg 230w, https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/MENU-350x438.jpg 350w, https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/MENU-480x600.jpg 480w, https:\/\/www.avvinamento.it\/wp-content\/uploads\/2025\/07\/MENU.jpg 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63ee829 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"63ee829\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a8b727 elementor-widget elementor-widget-spacer\" data-id=\"7a8b727\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ed eccoci giunti alla terza serata. Le nostre papille gustative saranno stuzzicate e coccolate dai piatti che ci verranno proposti dal Ristorante<\/p>\n","protected":false},"author":1,"featured_media":1023,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-past"],"_links":{"self":[{"href":"https:\/\/www.avvinamento.it\/index.php\/wp-json\/wp\/v2\/posts\/1022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.avvinamento.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.avvinamento.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.avvinamento.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.avvinamento.it\/index.php\/wp-json\/wp\/v2\/comments?post=1022"}],"version-history":[{"count":8,"href":"https:\/\/www.avvinamento.it\/index.php\/wp-json\/wp\/v2\/posts\/1022\/revisions"}],"predecessor-version":[{"id":1045,"href":"https:\/\/www.avvinamento.it\/index.php\/wp-json\/wp\/v2\/posts\/1022\/revisions\/1045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.avvinamento.it\/index.php\/wp-json\/wp\/v2\/media\/1023"}],"wp:attachment":[{"href":"https:\/\/www.avvinamento.it\/index.php\/wp-json\/wp\/v2\/media?parent=1022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.avvinamento.it\/index.php\/wp-json\/wp\/v2\/categories?post=1022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.avvinamento.it\/index.php\/wp-json\/wp\/v2\/tags?post=1022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}